{"id":17767,"date":"2026-03-06T16:00:24","date_gmt":"2026-03-06T22:00:24","guid":{"rendered":"https:\/\/educacion.seducoahuila.gob.mx\/?p=17767"},"modified":"2026-03-06T16:07:24","modified_gmt":"2026-03-06T22:07:24","slug":"acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila","status":"publish","type":"post","link":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/","title":{"rendered":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17767\" class=\"elementor elementor-17767\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f3b0dc1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3f3b0dc1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e008765 elementor-grid-0 elementor-widget elementor-widget-wpr-sharing-buttons\" data-id=\"e008765\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-sharing-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpr-sharing-buttons elementor-grid wpr-sharing-official wpr-sharing-label-off wpr-sharing-label-tr\"><div class=\"elementor-grid-item\"><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/\" class=\"wpr-sharing-icon wpr-sharing-facebook-f\" title=\"\" target=\"_blank\"><i class=\"fab fa-facebook-f\"><\/i><\/a><\/div><div class=\"elementor-grid-item\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/&title=Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila&summary=Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de Educaci\u00f3n B\u00e1sica 2026 CONVOCAN Al personal con funci\u00f3n docente, t\u00e9cnico docente, de direcci\u00f3n, de supervisi\u00f3n o de asesor\u00eda t\u00e9cnica pedag\u00f3gica de Educaci\u00f3n B\u00e1sica en servicio en Coahuila, a participar en las siguientes acciones de formaci\u00f3n para su formaci\u00f3n continua; de acuerdo con las siguientes especificaciones: Ver convocatoria&source=https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/\" class=\"wpr-sharing-icon wpr-sharing-linkedin-in\" title=\"\" target=\"_blank\"><i class=\"fab fa-linkedin-in\"><\/i><\/a><\/div><div class=\"elementor-grid-item\"><a href=\"https:\/\/api.whatsapp.com\/send?text=*Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila*%0ahttps:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/\" class=\"wpr-sharing-icon wpr-sharing-whatsapp\" title=\"\" target=\"_blank\"><i class=\"fab fa-whatsapp\"><\/i><\/a><\/div><div class=\"elementor-grid-item\"><a href=\"https:\/\/telegram.me\/share\/url?url=https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/&text=Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de Educaci\u00f3n B\u00e1sica 2026 CONVOCAN Al personal con funci\u00f3n docente, t\u00e9cnico docente, de direcci\u00f3n, de supervisi\u00f3n o de asesor\u00eda t\u00e9cnica pedag\u00f3gica de Educaci\u00f3n B\u00e1sica en servicio en Coahuila, a participar en las siguientes acciones de formaci\u00f3n para su formaci\u00f3n continua; de acuerdo con las siguientes especificaciones: Ver convocatoria\" class=\"wpr-sharing-icon wpr-sharing-telegram\" title=\"\" target=\"_blank\"><i class=\"fab fa-telegram\"><\/i><\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6787db84 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6787db84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/educacion.seducoahuila.gob.mx\/\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-double-left\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M223.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L319.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L393.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34zm-192 34l136 136c9.4 9.4 24.6 9.4 33.9 0l22.6-22.6c9.4-9.4 9.4-24.6 0-33.9L127.9 256l96.4-96.4c9.4-9.4 9.4-24.6 0-33.9L201.7 103c-9.4-9.4-24.6-9.4-33.9 0l-136 136c-9.5 9.4-9.5 24.6-.1 34z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7941ac4 elementor-widget elementor-widget-heading\" data-id=\"7941ac4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-236c63e elementor-widget elementor-widget-image\" data-id=\"236c63e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"872\" height=\"450\" src=\"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2026\/03\/convocatoria_acciones_formacion_2026.jpg\" class=\"attachment-large size-large wp-image-17768\" alt=\"\" srcset=\"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2026\/03\/convocatoria_acciones_formacion_2026.jpg 872w, https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2026\/03\/convocatoria_acciones_formacion_2026-300x155.jpg 300w, https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2026\/03\/convocatoria_acciones_formacion_2026-768x396.jpg 768w, https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2026\/03\/convocatoria_acciones_formacion_2026-600x310.jpg 600w\" sizes=\"(max-width: 872px) 100vw, 872px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eff6089 elementor-widget elementor-widget-text-editor\" data-id=\"eff6089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de Educaci\u00f3n B\u00e1sica 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61f9e50 elementor-widget elementor-widget-heading\" data-id=\"61f9e50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONVOCAN <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad95ff4 elementor-widget elementor-widget-text-editor\" data-id=\"ad95ff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al personal con funci\u00f3n docente, t\u00e9cnico docente, de direcci\u00f3n, de supervisi\u00f3n o de asesor\u00eda t\u00e9cnica pedag\u00f3gica de Educaci\u00f3n B\u00e1sica en servicio en Coahuila, a participar en las siguientes acciones de formaci\u00f3n para su formaci\u00f3n continua; de acuerdo con las siguientes especificaciones:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9726225 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"9726225\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/iddiec.edu.mx\/nueva\/edo01-26.html?utm_source=websria&#038;utm_medium=comunicacion&#038;utm_campaign=edo-0126#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver convocatoria<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de Educaci\u00f3n B\u00e1sica 2026 CONVOCAN Al personal con funci\u00f3n docente, t\u00e9cnico docente, de direcci\u00f3n, de supervisi\u00f3n o de asesor\u00eda t\u00e9cnica pedag\u00f3gica de Educaci\u00f3n B\u00e1sica en servicio en Coahuila, a participar en las siguientes acciones de formaci\u00f3n para su formaci\u00f3n continua; de acuerdo con las siguientes especificaciones: Ver convocatoria<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_17767\" class=\"pvc_stats all  \" data-element-id=\"17767\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":17768,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"two_page_speed":[],"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[28,41,70,62,64,59,60,22,61],"tags":[],"class_list":["post-17767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-docente","category-educacion-basica","category-iddiec","category-inicial","category-laborales","category-pree","category-prim","category-relevante","category-secu"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"SE_Admin_sitio\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<!-- Google tag (gtag.js) --> <script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-GP4L2L8GPW\"><\/script> <script> window.dataLayer = window.dataLayer || []; function gtag(){dataLayer.push(arguments);} gtag('js', new Date()); gtag('config', 'G-GP4L2L8GPW'); <\/script>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila | Sitio Oficial de la Secretar\u00eda de Educaci\u00f3n Coahuila\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila | Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila\" \/>\n\t\t<meta property=\"og:description\" content=\"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2022\/05\/cropped-cropped-LOGO-17.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2022\/05\/cropped-cropped-LOGO-17.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-06T22:00:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-06T22:07:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila | Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2022\/05\/cropped-cropped-LOGO-17.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#blogposting\",\"name\":\"Acciones de Formaci\\u00f3n a maestras y maestros en servicio de educaci\\u00f3n b\\u00e1sica en Coahuila | Secretar\\u00eda de Educaci\\u00f3n del Estado de Coahuila\",\"headline\":\"Acciones de Formaci\\u00f3n a maestras y maestros en servicio de educaci\\u00f3n b\\u00e1sica en Coahuila\",\"author\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/author\\\/se_admin_sitio\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/convocatoria_acciones_formacion_2026.jpg\",\"width\":872,\"height\":450},\"datePublished\":\"2026-03-06T16:00:24-06:00\",\"dateModified\":\"2026-03-06T16:07:24-06:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#webpage\"},\"articleSection\":\"Docente, Educaci\\u00f3n basica, IDDIEC, Inicial, Laborales, Preescolar, Primaria, Relevante, Secundaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/#listItem\",\"name\":\"Educaci\\u00f3n basica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/#listItem\",\"position\":2,\"name\":\"Educaci\\u00f3n basica\",\"item\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/pree\\\/#listItem\",\"name\":\"Preescolar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/pree\\\/#listItem\",\"position\":3,\"name\":\"Preescolar\",\"item\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/pree\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#listItem\",\"name\":\"Acciones de Formaci\\u00f3n a maestras y maestros en servicio de educaci\\u00f3n b\\u00e1sica en Coahuila\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/#listItem\",\"name\":\"Educaci\\u00f3n basica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#listItem\",\"position\":4,\"name\":\"Acciones de Formaci\\u00f3n a maestras y maestros en servicio de educaci\\u00f3n b\\u00e1sica en Coahuila\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/category\\\/educacion-basica\\\/pree\\\/#listItem\",\"name\":\"Preescolar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/#organization\",\"name\":\"Secretar\\u00eda de Educaci\\u00f3n del Estado de Coahuila\",\"description\":\"Sitio Oficial de la Secretar\\u00eda de Educaci\\u00f3n Coahuila\",\"url\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/\",\"telephone\":\"+528444180000\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-LOGO-17.png\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#organizationLogo\",\"width\":2803,\"height\":1063},\"image\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/author\\\/se_admin_sitio\\\/#author\",\"url\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/author\\\/se_admin_sitio\\\/\",\"name\":\"SE_Admin_sitio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd4769e67d4bbe1719279d9e290581c20f587133c25d94008b92fa57b37aada9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"SE_Admin_sitio\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#webpage\",\"url\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/\",\"name\":\"Acciones de Formaci\\u00f3n a maestras y maestros en servicio de educaci\\u00f3n b\\u00e1sica en Coahuila | Secretar\\u00eda de Educaci\\u00f3n del Estado de Coahuila\",\"description\":\"Acciones de Formaci\\u00f3n a maestras y maestros en servicio de educaci\\u00f3n b\\u00e1sica en Coahuila La Secretar\\u00eda de Educaci\\u00f3n del Estado de Coahuila de Zaragoza, a trav\\u00e9s de la Subsecretar\\u00eda de Educaci\\u00f3n B\\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\\u00f3n, Evaluaci\\u00f3n y Certificaci\\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\\u00f3n Continua de\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/author\\\/se_admin_sitio\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/author\\\/se_admin_sitio\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/convocatoria_acciones_formacion_2026.jpg\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#mainImage\",\"width\":872,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/index.php\\\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\\\/#mainImage\"},\"datePublished\":\"2026-03-06T16:00:24-06:00\",\"dateModified\":\"2026-03-06T16:07:24-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/#website\",\"url\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/\",\"name\":\"Secretaria de Educacion del Estado de Coahuila\",\"description\":\"Sitio Oficial de la Secretar\\u00eda de Educaci\\u00f3n Coahuila\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/educacion.seducoahuila.gob.mx\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila | Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila","description":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de","canonical_url":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt; &lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-GP4L2L8GPW\"&gt;&lt;\/script&gt; &lt;script&gt; window.dataLayer = window.dataLayer || []; function gtag(){dataLayer.push(arguments);} gtag('js', new Date()); gtag('config', 'G-GP4L2L8GPW'); &lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#blogposting","name":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila | Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila","headline":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila","author":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/author\/se_admin_sitio\/#author"},"publisher":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2026\/03\/convocatoria_acciones_formacion_2026.jpg","width":872,"height":450},"datePublished":"2026-03-06T16:00:24-06:00","dateModified":"2026-03-06T16:07:24-06:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#webpage"},"isPartOf":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#webpage"},"articleSection":"Docente, Educaci\u00f3n basica, IDDIEC, Inicial, Laborales, Preescolar, Primaria, Relevante, Secundaria"},{"@type":"BreadcrumbList","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx#listItem","position":1,"name":"Home","item":"https:\/\/educacion.seducoahuila.gob.mx","nextItem":{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/#listItem","name":"Educaci\u00f3n basica"}},{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/#listItem","position":2,"name":"Educaci\u00f3n basica","item":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/pree\/#listItem","name":"Preescolar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/pree\/#listItem","position":3,"name":"Preescolar","item":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/pree\/","nextItem":{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#listItem","name":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila"},"previousItem":{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/#listItem","name":"Educaci\u00f3n basica"}},{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#listItem","position":4,"name":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila","previousItem":{"@type":"ListItem","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/pree\/#listItem","name":"Preescolar"}}]},{"@type":"Organization","@id":"https:\/\/educacion.seducoahuila.gob.mx\/#organization","name":"Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila","description":"Sitio Oficial de la Secretar\u00eda de Educaci\u00f3n Coahuila","url":"https:\/\/educacion.seducoahuila.gob.mx\/","telephone":"+528444180000","logo":{"@type":"ImageObject","url":"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2022\/05\/cropped-LOGO-17.png","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#organizationLogo","width":2803,"height":1063},"image":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/author\/se_admin_sitio\/#author","url":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/author\/se_admin_sitio\/","name":"SE_Admin_sitio","image":{"@type":"ImageObject","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/bd4769e67d4bbe1719279d9e290581c20f587133c25d94008b92fa57b37aada9?s=96&d=mm&r=g","width":96,"height":96,"caption":"SE_Admin_sitio"}},{"@type":"WebPage","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#webpage","url":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/","name":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila | Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila","description":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/#website"},"breadcrumb":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#breadcrumblist"},"author":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/author\/se_admin_sitio\/#author"},"creator":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/author\/se_admin_sitio\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2026\/03\/convocatoria_acciones_formacion_2026.jpg","@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#mainImage","width":872,"height":450},"primaryImageOfPage":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/#mainImage"},"datePublished":"2026-03-06T16:00:24-06:00","dateModified":"2026-03-06T16:07:24-06:00"},{"@type":"WebSite","@id":"https:\/\/educacion.seducoahuila.gob.mx\/#website","url":"https:\/\/educacion.seducoahuila.gob.mx\/","name":"Secretaria de Educacion del Estado de Coahuila","description":"Sitio Oficial de la Secretar\u00eda de Educaci\u00f3n Coahuila","inLanguage":"es-MX","publisher":{"@id":"https:\/\/educacion.seducoahuila.gob.mx\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila | Sitio Oficial de la Secretar\u00eda de Educaci\u00f3n Coahuila","og:type":"article","og:title":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila | Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila","og:description":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de","og:url":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/","og:image":"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2022\/05\/cropped-cropped-LOGO-17.png","og:image:secure_url":"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2022\/05\/cropped-cropped-LOGO-17.png","og:image:width":512,"og:image:height":512,"article:published_time":"2026-03-06T22:00:24+00:00","article:modified_time":"2026-03-06T22:07:24+00:00","twitter:card":"summary","twitter:title":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila | Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila","twitter:description":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza, a trav\u00e9s de la Subsecretar\u00eda de Educaci\u00f3n B\u00e1sica y del Instituto de Desarrollo Docente, Investigaci\u00f3n, Evaluaci\u00f3n y Certificaci\u00f3n, con fundamento en lo establecido en la Estrategia Nacional de Formaci\u00f3n Continua de","twitter:image":"https:\/\/educacion.seducoahuila.gob.mx\/wp-content\/uploads\/2022\/05\/cropped-cropped-LOGO-17.png"},"aioseo_meta_data":{"post_id":"17767","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-06 22:00:28","updated":"2026-03-06 22:08:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/educacion.seducoahuila.gob.mx\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/\" title=\"Educaci\u00f3n basica\">Educaci\u00f3n basica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/pree\/\" title=\"Preescolar\">Preescolar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAcciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/educacion.seducoahuila.gob.mx"},{"label":"Educaci\u00f3n basica","link":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/"},{"label":"Preescolar","link":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/category\/educacion-basica\/pree\/"},{"label":"Acciones de Formaci\u00f3n a maestras y maestros en servicio de educaci\u00f3n b\u00e1sica en Coahuila","link":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/acciones-de-formacion-a-maestras-y-maestros-en-servicio-de-educacion-basica-en-coahuila\/"}],"a3_pvc":{"activated":true,"total_views":0,"today_views":0},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:23:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/17767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/comments?post=17767"}],"version-history":[{"count":4,"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/17767\/revisions"}],"predecessor-version":[{"id":17773,"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/17767\/revisions\/17773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/media\/17768"}],"wp:attachment":[{"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/media?parent=17767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/categories?post=17767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/educacion.seducoahuila.gob.mx\/index.php\/wp-json\/wp\/v2\/tags?post=17767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}